{"id":425,"date":"1968-09-24T00:00:49","date_gmt":"1968-09-23T17:00:49","guid":{"rendered":"https:\/\/web-kadin.kadinevolve.id\/?page_id=425"},"modified":"2023-03-10T16:27:24","modified_gmt":"2023-03-10T09:27:24","slug":"sulsel","status":"publish","type":"page","link":"https:\/\/web-kadin.kadinevolve.id\/en\/sulsel\/","title":{"rendered":"Sulawesi Selatan"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":911,"featured_media":487,"parent":0,"menu_order":25,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-425","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sulawesi Selatan - KADIN Indonesia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web-kadin.kadinevolve.id\/en\/sulsel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sulawesi Selatan - KADIN Indonesia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web-kadin.kadinevolve.id\/en\/sulsel\/\" \/>\n<meta property=\"og:site_name\" content=\"KADIN Indonesia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-10T09:27:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web-kadin.kadinevolve.id\/wp-content\/uploads\/kadinda-sul-sel.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/sulsel\\\/\",\"url\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/sulsel\\\/\",\"name\":\"Sulawesi Selatan - KADIN Indonesia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/sulsel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/sulsel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/wp-content\\\/uploads\\\/kadinda-sul-sel.png\",\"datePublished\":\"1968-09-23T17:00:49+00:00\",\"dateModified\":\"2023-03-10T09:27:24+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/sulsel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/sulsel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/wp-content\\\/uploads\\\/kadinda-sul-sel.png\",\"contentUrl\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/wp-content\\\/uploads\\\/kadinda-sul-sel.png\",\"width\":512,\"height\":512,\"caption\":\"Sulawesi Selatan\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/#website\",\"url\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/\",\"name\":\"KADIN Indonesia\",\"description\":\"Kamar Dagang dan Industri Indonesia (Indonesian Chamber of Commerce and Industry)\",\"publisher\":{\"@id\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/#organization\",\"name\":\"KADIN Indonesia\",\"url\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/wp-content\\\/uploads\\\/kadin-logo.png\",\"contentUrl\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/wp-content\\\/uploads\\\/kadin-logo.png\",\"width\":512,\"height\":512,\"caption\":\"KADIN Indonesia\"},\"image\":{\"@id\":\"https:\\\/\\\/web-kadin.kadinevolve.id\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sulawesi Selatan - KADIN Indonesia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web-kadin.kadinevolve.id\/en\/sulsel\/","og_locale":"en_US","og_type":"article","og_title":"Sulawesi Selatan - KADIN Indonesia","og_url":"https:\/\/web-kadin.kadinevolve.id\/en\/sulsel\/","og_site_name":"KADIN Indonesia","article_modified_time":"2023-03-10T09:27:24+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/web-kadin.kadinevolve.id\/wp-content\/uploads\/kadinda-sul-sel.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/web-kadin.kadinevolve.id\/sulsel\/","url":"https:\/\/web-kadin.kadinevolve.id\/sulsel\/","name":"Sulawesi Selatan - KADIN Indonesia","isPartOf":{"@id":"https:\/\/web-kadin.kadinevolve.id\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web-kadin.kadinevolve.id\/sulsel\/#primaryimage"},"image":{"@id":"https:\/\/web-kadin.kadinevolve.id\/sulsel\/#primaryimage"},"thumbnailUrl":"https:\/\/web-kadin.kadinevolve.id\/wp-content\/uploads\/kadinda-sul-sel.png","datePublished":"1968-09-23T17:00:49+00:00","dateModified":"2023-03-10T09:27:24+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web-kadin.kadinevolve.id\/sulsel\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/web-kadin.kadinevolve.id\/sulsel\/#primaryimage","url":"https:\/\/web-kadin.kadinevolve.id\/wp-content\/uploads\/kadinda-sul-sel.png","contentUrl":"https:\/\/web-kadin.kadinevolve.id\/wp-content\/uploads\/kadinda-sul-sel.png","width":512,"height":512,"caption":"Sulawesi Selatan"},{"@type":"WebSite","@id":"https:\/\/web-kadin.kadinevolve.id\/#website","url":"https:\/\/web-kadin.kadinevolve.id\/","name":"KADIN Indonesia","description":"Kamar Dagang dan Industri Indonesia (Indonesian Chamber of Commerce and Industry)","publisher":{"@id":"https:\/\/web-kadin.kadinevolve.id\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web-kadin.kadinevolve.id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/web-kadin.kadinevolve.id\/#organization","name":"KADIN Indonesia","url":"https:\/\/web-kadin.kadinevolve.id\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/web-kadin.kadinevolve.id\/#\/schema\/logo\/image\/","url":"https:\/\/web-kadin.kadinevolve.id\/wp-content\/uploads\/kadin-logo.png","contentUrl":"https:\/\/web-kadin.kadinevolve.id\/wp-content\/uploads\/kadin-logo.png","width":512,"height":512,"caption":"KADIN Indonesia"},"image":{"@id":"https:\/\/web-kadin.kadinevolve.id\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/web-kadin.kadinevolve.id\/en\/wp-json\/wp\/v2\/pages\/425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web-kadin.kadinevolve.id\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/web-kadin.kadinevolve.id\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/web-kadin.kadinevolve.id\/en\/wp-json\/wp\/v2\/users\/911"}],"replies":[{"embeddable":true,"href":"https:\/\/web-kadin.kadinevolve.id\/en\/wp-json\/wp\/v2\/comments?post=425"}],"version-history":[{"count":0,"href":"https:\/\/web-kadin.kadinevolve.id\/en\/wp-json\/wp\/v2\/pages\/425\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web-kadin.kadinevolve.id\/en\/wp-json\/wp\/v2\/media\/487"}],"wp:attachment":[{"href":"https:\/\/web-kadin.kadinevolve.id\/en\/wp-json\/wp\/v2\/media?parent=425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}